{"id":189,"count":1,"description":"","link":"https:\/\/neroo-speak.com\/learn-english\/tag\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\/","name":"\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631","slug":"%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"o8NJg7gb83rDrOTaBelaV30CRE01O4P2wavDT1oIL44\" \/>\n\t<meta name=\"msvalidate.01\" content=\"257F4753B56E99498E6323D7C6168240\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/neroo-speak.com\/learn-english\/tag\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/189\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/tag\\\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\\\/#listItem\",\"name\":\"\\u0627\\u0644\\u0644\\u063a\\u0629 \\u0627\\u0644\\u0627\\u0646\\u062c\\u0644\\u064a\\u0632\\u064a\\u0629 \\u0641\\u064a \\u0627\\u0644\\u0645\\u0637\\u0627\\u0631\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/tag\\\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\\\/#listItem\",\"position\":2,\"name\":\"\\u0627\\u0644\\u0644\\u063a\\u0629 \\u0627\\u0644\\u0627\\u0646\\u062c\\u0644\\u064a\\u0632\\u064a\\u0629 \\u0641\\u064a \\u0627\\u0644\\u0645\\u0637\\u0627\\u0631\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/189\\\/#collectionpage\",\"url\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/189\\\/\",\"name\":\"\\u0627\\u0644\\u0644\\u063a\\u0629 \\u0627\\u0644\\u0627\\u0646\\u062c\\u0644\\u064a\\u0632\\u064a\\u0629 \\u0641\\u064a \\u0627\\u0644\\u0645\\u0637\\u0627\\u0631 | \\u062a\\u0637\\u0628\\u064a\\u0642 \\u062a\\u0639\\u0644\\u0645 \\u0627\\u0644\\u0627\\u0646\\u062c\\u0644\\u064a\\u0632\\u064a\\u0629\",\"inLanguage\":\"ar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/189\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/#organization\",\"name\":\"\\u062a\\u0637\\u0628\\u064a\\u0642 \\u062a\\u0639\\u0644\\u0645 \\u0627\\u0644\\u0627\\u0646\\u062c\\u0644\\u064a\\u0632\\u064a\\u0629\",\"url\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/#website\",\"url\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/\",\"name\":\"\\u062a\\u0637\\u0628\\u064a\\u0642 \\u062a\\u0639\\u0644\\u0645 \\u0627\\u0644\\u0627\\u0646\\u062c\\u0644\\u064a\\u0632\\u064a\\u0629\",\"inLanguage\":\"ar\",\"publisher\":{\"@id\":\"https:\\\/\\\/neroo-speak.com\\\/learn-english\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631 | \u062a\u0637\u0628\u064a\u0642 \u062a\u0639\u0644\u0645 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629","description":"","canonical_url":"https:\/\/neroo-speak.com\/learn-english\/tag\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"o8NJg7gb83rDrOTaBelaV30CRE01O4P2wavDT1oIL44","msvalidate.01":"257F4753B56E99498E6323D7C6168240","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/tags\/189\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/neroo-speak.com\/learn-english#listItem","position":1,"name":"Home","item":"https:\/\/neroo-speak.com\/learn-english","nextItem":{"@type":"ListItem","@id":"https:\/\/neroo-speak.com\/learn-english\/tag\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\/#listItem","name":"\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631"}},{"@type":"ListItem","@id":"https:\/\/neroo-speak.com\/learn-english\/tag\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\/#listItem","position":2,"name":"\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631","previousItem":{"@type":"ListItem","@id":"https:\/\/neroo-speak.com\/learn-english#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/tags\/189\/#collectionpage","url":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/tags\/189\/","name":"\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631 | \u062a\u0637\u0628\u064a\u0642 \u062a\u0639\u0644\u0645 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629","inLanguage":"ar","isPartOf":{"@id":"https:\/\/neroo-speak.com\/learn-english\/#website"},"breadcrumb":{"@id":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/tags\/189\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/neroo-speak.com\/learn-english\/#organization","name":"\u062a\u0637\u0628\u064a\u0642 \u062a\u0639\u0644\u0645 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629","url":"https:\/\/neroo-speak.com\/learn-english\/"},{"@type":"WebSite","@id":"https:\/\/neroo-speak.com\/learn-english\/#website","url":"https:\/\/neroo-speak.com\/learn-english\/","name":"\u062a\u0637\u0628\u064a\u0642 \u062a\u0639\u0644\u0645 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629","inLanguage":"ar","publisher":{"@id":"https:\/\/neroo-speak.com\/learn-english\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/neroo-speak.com\/learn-english\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/neroo-speak.com\/learn-english"},{"label":"\u0627\u0644\u0644\u063a\u0629 \u0627\u0644\u0627\u0646\u062c\u0644\u064a\u0632\u064a\u0629 \u0641\u064a \u0627\u0644\u0645\u0637\u0627\u0631","link":"https:\/\/neroo-speak.com\/learn-english\/tag\/%d8%a7%d9%84%d9%84%d8%ba%d8%a9-%d8%a7%d9%84%d8%a7%d9%86%d8%ac%d9%84%d9%8a%d8%b2%d9%8a%d8%a9-%d9%81%d9%8a-%d8%a7%d9%84%d9%85%d8%b7%d8%a7%d8%b1\/"}],"_links":{"self":[{"href":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/tags\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/neroo-speak.com\/learn-english\/wp-json\/wp\/v2\/posts?tags=189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}